
{"id":2604,"date":"2019-02-22T10:11:39","date_gmt":"2019-02-22T15:11:39","guid":{"rendered":"https:\/\/washingtonnational.com\/business-owners\/health-insurance\/"},"modified":"2024-10-17T10:11:29","modified_gmt":"2024-10-17T14:11:29","slug":"seguro-de-salud","status":"publish","type":"page","link":"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/","title":{"rendered":"Seguro de salud"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Washington National ofrece un seguro de salud complementario para su negocio y sus empleados. Los productos incluyen seguro contra accidentes, seguro por discapacidad, seguro contra el c\u00e1ncer, seguro contra enfermedades graves y seguro de hospitalizaci\u00f3n y UCI.<br \/>\n [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/\">Leer m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"author":21,"featured_media":0,"parent":2601,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2604","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Seguro m\u00e9dico para empresarios y empleados - Washington National<\/title>\n<meta name=\"description\" content=\"Washington National ofrece un seguro de salud complementario para su negocio y sus empleados. Los productos incluyen seguro contra accidentes, seguro por discapacidad, seguro contra el c\u00e1ncer, seguro contra enfermedades graves y seguro de hospitalizaci\u00f3n y UCI.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seguro de salud\" \/>\n<meta property=\"og:description\" content=\"Washington National ofrece un seguro de salud complementario para su negocio y sus empleados. Los productos incluyen seguro contra accidentes, seguro por discapacidad, seguro contra el c\u00e1ncer, seguro contra enfermedades graves y seguro de hospitalizaci\u00f3n y UCI.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Washington National\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WashingtonNational\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-17T14:11:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/empresarios\\\/seguro-de-salud\\\/\",\"url\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/empresarios\\\/seguro-de-salud\\\/\",\"name\":\"Seguro m\u00e9dico para empresarios y empleados - Washington National\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#website\"},\"datePublished\":\"2019-02-22T15:11:39+00:00\",\"dateModified\":\"2024-10-17T14:11:29+00:00\",\"description\":\"Washington National ofrece un seguro de salud complementario para su negocio y sus empleados. Los productos incluyen seguro contra accidentes, seguro por discapacidad, seguro contra el c\u00e1ncer, seguro contra enfermedades graves y seguro de hospitalizaci\u00f3n y UCI.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/empresarios\\\/seguro-de-salud\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/washingtonnational.com\\\/es\\\/empresarios\\\/seguro-de-salud\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/empresarios\\\/seguro-de-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresarios\",\"item\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/empresarios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seguro de salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/\",\"name\":\"Washington National\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#organization\",\"name\":\"Washington National Insurance Company\",\"url\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/washingtonnational.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/WN_RGB_TRANS2.png\",\"contentUrl\":\"https:\\\/\\\/washingtonnational.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/WN_RGB_TRANS2.png\",\"width\":582,\"height\":319,\"caption\":\"Washington National Insurance Company\"},\"image\":{\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WashingtonNational\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/washington-national-insurance-company\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WashingtonNational\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Seguro m\u00e9dico para empresarios y empleados - Washington National","description":"Washington National ofrece un seguro de salud complementario para su negocio y sus empleados. Los productos incluyen seguro contra accidentes, seguro por discapacidad, seguro contra el c\u00e1ncer, seguro contra enfermedades graves y seguro de hospitalizaci\u00f3n y UCI.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/","og_locale":"es_ES","og_type":"article","og_title":"Seguro de salud","og_description":"Washington National ofrece un seguro de salud complementario para su negocio y sus empleados. Los productos incluyen seguro contra accidentes, seguro por discapacidad, seguro contra el c\u00e1ncer, seguro contra enfermedades graves y seguro de hospitalizaci\u00f3n y UCI.","og_url":"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/","og_site_name":"Washington National","article_publisher":"https:\/\/www.facebook.com\/WashingtonNational","article_modified_time":"2024-10-17T14:11:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/","url":"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/","name":"Seguro m\u00e9dico para empresarios y empleados - Washington National","isPartOf":{"@id":"https:\/\/washingtonnational.com\/es\/#website"},"datePublished":"2019-02-22T15:11:39+00:00","dateModified":"2024-10-17T14:11:29+00:00","description":"Washington National ofrece un seguro de salud complementario para su negocio y sus empleados. Los productos incluyen seguro contra accidentes, seguro por discapacidad, seguro contra el c\u00e1ncer, seguro contra enfermedades graves y seguro de hospitalizaci\u00f3n y UCI.","breadcrumb":{"@id":"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/washingtonnational.com\/es\/empresarios\/seguro-de-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/washingtonnational.com\/es\/"},{"@type":"ListItem","position":2,"name":"Empresarios","item":"https:\/\/washingtonnational.com\/es\/empresarios\/"},{"@type":"ListItem","position":3,"name":"Seguro de salud"}]},{"@type":"WebSite","@id":"https:\/\/washingtonnational.com\/es\/#website","url":"https:\/\/washingtonnational.com\/es\/","name":"Washington National","description":"","publisher":{"@id":"https:\/\/washingtonnational.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/washingtonnational.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/washingtonnational.com\/es\/#organization","name":"Washington National Insurance Company","url":"https:\/\/washingtonnational.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/washingtonnational.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/washingtonnational.com\/wp-content\/uploads\/2019\/03\/WN_RGB_TRANS2.png","contentUrl":"https:\/\/washingtonnational.com\/wp-content\/uploads\/2019\/03\/WN_RGB_TRANS2.png","width":582,"height":319,"caption":"Washington National Insurance Company"},"image":{"@id":"https:\/\/washingtonnational.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WashingtonNational","https:\/\/www.linkedin.com\/company\/washington-national-insurance-company\/","https:\/\/www.youtube.com\/user\/WashingtonNational\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages\/2604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/comments?post=2604"}],"version-history":[{"count":6,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages\/2604\/revisions"}],"predecessor-version":[{"id":7077,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages\/2604\/revisions\/7077"}],"up":[{"embeddable":true,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages\/2601"}],"wp:attachment":[{"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/media?parent=2604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}