
{"id":2653,"date":"2019-02-22T10:05:58","date_gmt":"2019-02-22T15:05:58","guid":{"rendered":"https:\/\/washingtonnational.com\/families-individuals\/life-insurance\/term-life\/"},"modified":"2023-08-24T09:34:42","modified_gmt":"2023-08-24T13:34:42","slug":"seguro-de-vida-termino","status":"publish","type":"page","link":"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/","title":{"rendered":"Seguro de vida a t\u00e9rmino"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>El seguro de vida a t\u00e9rmino de Washington National le ofrece una protecci\u00f3n de vida a t\u00e9rmino asequible que evoluciona con sus necesidades cambiantes durante sus a\u00f1os de trabajo y en la jubilaci\u00f3n.<br \/>\n [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/\">Leer m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"author":21,"featured_media":0,"parent":2648,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2653","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Seguro de vida a t\u00e9rmino - Washington National<\/title>\n<meta name=\"description\" content=\"El seguro de vida a t\u00e9rmino de Washington National le ofrece una protecci\u00f3n de vida a t\u00e9rmino asequible que evoluciona con sus necesidades cambiantes durante sus a\u00f1os de trabajo y en la jubilaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seguro de vida a t\u00e9rmino\" \/>\n<meta property=\"og:description\" content=\"El seguro de vida a t\u00e9rmino de Washington National le ofrece una protecci\u00f3n de vida a t\u00e9rmino asequible que evoluciona con sus necesidades cambiantes durante sus a\u00f1os de trabajo y en la jubilaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/\" \/>\n<meta property=\"og:site_name\" content=\"Washington National\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WashingtonNational\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-24T13:34:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/familias-personas\\\/seguro-de-vida\\\/seguro-de-vida-termino\\\/\",\"url\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/familias-personas\\\/seguro-de-vida\\\/seguro-de-vida-termino\\\/\",\"name\":\"Seguro de vida a t\u00e9rmino - Washington National\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#website\"},\"datePublished\":\"2019-02-22T15:05:58+00:00\",\"dateModified\":\"2023-08-24T13:34:42+00:00\",\"description\":\"El seguro de vida a t\u00e9rmino de Washington National le ofrece una protecci\u00f3n de vida a t\u00e9rmino asequible que evoluciona con sus necesidades cambiantes durante sus a\u00f1os de trabajo y en la jubilaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/familias-personas\\\/seguro-de-vida\\\/seguro-de-vida-termino\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/washingtonnational.com\\\/es\\\/familias-personas\\\/seguro-de-vida\\\/seguro-de-vida-termino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/familias-personas\\\/seguro-de-vida\\\/seguro-de-vida-termino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Familias y personas\",\"item\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/familias-personas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seguro de vida\",\"item\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/familias-personas\\\/seguro-de-vida\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Seguro de vida a t\u00e9rmino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/\",\"name\":\"Washington National\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#organization\",\"name\":\"Washington National Insurance Company\",\"url\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/washingtonnational.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/WN_RGB_TRANS2.png\",\"contentUrl\":\"https:\\\/\\\/washingtonnational.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/WN_RGB_TRANS2.png\",\"width\":582,\"height\":319,\"caption\":\"Washington National Insurance Company\"},\"image\":{\"@id\":\"https:\\\/\\\/washingtonnational.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WashingtonNational\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/washington-national-insurance-company\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WashingtonNational\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Seguro de vida a t\u00e9rmino - Washington National","description":"El seguro de vida a t\u00e9rmino de Washington National le ofrece una protecci\u00f3n de vida a t\u00e9rmino asequible que evoluciona con sus necesidades cambiantes durante sus a\u00f1os de trabajo y en la jubilaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/","og_locale":"es_ES","og_type":"article","og_title":"Seguro de vida a t\u00e9rmino","og_description":"El seguro de vida a t\u00e9rmino de Washington National le ofrece una protecci\u00f3n de vida a t\u00e9rmino asequible que evoluciona con sus necesidades cambiantes durante sus a\u00f1os de trabajo y en la jubilaci\u00f3n.","og_url":"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/","og_site_name":"Washington National","article_publisher":"https:\/\/www.facebook.com\/WashingtonNational","article_modified_time":"2023-08-24T13:34:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/","url":"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/","name":"Seguro de vida a t\u00e9rmino - Washington National","isPartOf":{"@id":"https:\/\/washingtonnational.com\/es\/#website"},"datePublished":"2019-02-22T15:05:58+00:00","dateModified":"2023-08-24T13:34:42+00:00","description":"El seguro de vida a t\u00e9rmino de Washington National le ofrece una protecci\u00f3n de vida a t\u00e9rmino asequible que evoluciona con sus necesidades cambiantes durante sus a\u00f1os de trabajo y en la jubilaci\u00f3n.","breadcrumb":{"@id":"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/seguro-de-vida-termino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/washingtonnational.com\/es\/"},{"@type":"ListItem","position":2,"name":"Familias y personas","item":"https:\/\/washingtonnational.com\/es\/familias-personas\/"},{"@type":"ListItem","position":3,"name":"Seguro de vida","item":"https:\/\/washingtonnational.com\/es\/familias-personas\/seguro-de-vida\/"},{"@type":"ListItem","position":4,"name":"Seguro de vida a t\u00e9rmino"}]},{"@type":"WebSite","@id":"https:\/\/washingtonnational.com\/es\/#website","url":"https:\/\/washingtonnational.com\/es\/","name":"Washington National","description":"","publisher":{"@id":"https:\/\/washingtonnational.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/washingtonnational.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/washingtonnational.com\/es\/#organization","name":"Washington National Insurance Company","url":"https:\/\/washingtonnational.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/washingtonnational.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/washingtonnational.com\/wp-content\/uploads\/2019\/03\/WN_RGB_TRANS2.png","contentUrl":"https:\/\/washingtonnational.com\/wp-content\/uploads\/2019\/03\/WN_RGB_TRANS2.png","width":582,"height":319,"caption":"Washington National Insurance Company"},"image":{"@id":"https:\/\/washingtonnational.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WashingtonNational","https:\/\/www.linkedin.com\/company\/washington-national-insurance-company\/","https:\/\/www.youtube.com\/user\/WashingtonNational\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages\/2653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/comments?post=2653"}],"version-history":[{"count":13,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages\/2653\/revisions"}],"predecessor-version":[{"id":6492,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages\/2653\/revisions\/6492"}],"up":[{"embeddable":true,"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/pages\/2648"}],"wp:attachment":[{"href":"https:\/\/washingtonnational.com\/es\/wp-json\/wp\/v2\/media?parent=2653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}